{"id":18286,"date":"2024-12-06T12:02:28","date_gmt":"2024-12-06T12:02:28","guid":{"rendered":"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24.jpg"},"modified":"2024-12-06T12:02:28","modified_gmt":"2024-12-06T12:02:28","slug":"alresford-xmas-24","status":"inherit","type":"attachment","link":"https:\/\/www.gcurley.info\/news\/2024\/12\/evangelism-speakers-corner-12\/alresford-xmas-24\/","title":{"rendered":"alresford xmas 24"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-18286","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24-300x169.jpg 300w, https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24-1024x576.jpg 1024w, https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24-768x432.jpg 768w, https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":720,"file":"2024\/12\/alresford-xmas-24.jpg","filesize":101129,"sizes":{"medium":{"file":"alresford-xmas-24-300x169.jpg","width":300,"height":169,"filesize":9496,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24-300x169.jpg"},"large":{"file":"alresford-xmas-24-1024x576.jpg","width":1024,"height":576,"filesize":51747,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24-1024x576.jpg"},"thumbnail":{"file":"alresford-xmas-24-150x150.jpg","width":150,"height":150,"filesize":5224,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24-150x150.jpg"},"medium_large":{"file":"alresford-xmas-24-768x432.jpg","width":768,"height":432,"filesize":34936,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24-768x432.jpg"},"gform-image-choice-sm":{"file":"alresford-xmas-24-300x300.jpg","width":300,"height":300,"filesize":12987,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24-300x300.jpg"},"gform-image-choice-md":{"file":"alresford-xmas-24-400x400.jpg","width":400,"height":400,"filesize":19073,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24-400x400.jpg"},"gform-image-choice-lg":{"file":"alresford-xmas-24-600x600.jpg","width":600,"height":600,"filesize":33857,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24-600x600.jpg"},"full":{"file":"alresford-xmas-24.jpg","width":1280,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":18285,"source_url":"https:\/\/www.gcurley.info\/news\/wp-content\/uploads\/2024\/12\/alresford-xmas-24.jpg","_links":{"self":[{"href":"https:\/\/www.gcurley.info\/news\/wp-json\/wp\/v2\/media\/18286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gcurley.info\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.gcurley.info\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.gcurley.info\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gcurley.info\/news\/wp-json\/wp\/v2\/comments?post=18286"}]}}